{"id":2602,"date":"2020-12-28T20:01:14","date_gmt":"2020-12-28T11:01:14","guid":{"rendered":"https:\/\/www.yotsuya-s.co.jp\/juken-match\/wp\/school\/%e6%9d%b1%e9%82%a6%e9%9f%b3%e6%a5%bd%e5%a4%a7%e5%ad%a6%e9%99%84%e5%b1%9e%e6%9d%b1%e9%82%a6%e4%b8%ad%e5%ad%a6%e6%a0%a1"},"modified":"2026-02-16T11:53:30","modified_gmt":"2026-02-16T02:53:30","slug":"%e6%9d%b1%e9%82%a6%e9%9f%b3%e6%a5%bd%e5%a4%a7%e5%ad%a6%e9%99%84%e5%b1%9e%e6%9d%b1%e9%82%a6%e4%b8%ad%e5%ad%a6%e6%a0%a1","status":"publish","type":"school","link":"https:\/\/www.yotsuya-s.co.jp\/juken-match\/school\/%e6%9d%b1%e9%82%a6%e9%9f%b3%e6%a5%bd%e5%a4%a7%e5%ad%a6%e9%99%84%e5%b1%9e%e6%9d%b1%e9%82%a6%e4%b8%ad%e5%ad%a6%e6%a0%a1\/","title":{"rendered":"\u6771\u90a6\u97f3\u697d\u5927\u5b66\u9644\u5c5e\u6771\u90a6\u4e2d\u5b66\u6821"},"excerpt":{"rendered":"\u6771\u90a6\u97f3\u697d\u5927\u5b66\u9644\u5c5e\u6771\u90a6\u4e2d\u5b66\u6821\u306b\u3064\u3044\u3066\u306e\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u3001\u4e2d\u5b66\u53d7\u9a13\u30de\u30c3\u30c1\u30f3\u30b0\u306e\u5b66\u6821\u8a73\u7d30\u30da\u30fc\u30b8\u3067\u3059\u3002\u4e2d\u5b66\u304b\u3089\u5927\u5b66\u9662\u307e\u3067\u306e\u97f3\u697d\u82b8\u8853\u4e00\u8cab\u6559\u80b2\u3092\u884c\u3046\u3002\u5927\u5b66\u30fb\u77ed\u5927\u306e\u6559\u6388\u9663\u304c\u30de\u30f3\u30c4\u30fc\u30de\u30f3\u3067\u6307\u5c0e\u3092\u884c\u3046\u97f3\u697d\u5b9f\u6280\u3068\u3068\u3082\u306b\u3001\u30d0\u30e9\u30f3\u30b9\u306e\u3068\u308c\u305f\u4eba\u683c\u306e\u80b2\u6210\u3092\u76ee\u6307\u3057\u3066\u4e00\u822c\u79d1\u76ee\u306b\u3082\u529b\u3092\u5165\u308c\u308b\u3002","protected":false},"featured_media":0,"template":"","format":"standard","class_list":["post-2602","school","type-school","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/www.yotsuya-s.co.jp\/juken-match\/wp-json\/wp\/v2\/school\/2602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yotsuya-s.co.jp\/juken-match\/wp-json\/wp\/v2\/school"}],"about":[{"href":"https:\/\/www.yotsuya-s.co.jp\/juken-match\/wp-json\/wp\/v2\/types\/school"}],"wp:attachment":[{"href":"https:\/\/www.yotsuya-s.co.jp\/juken-match\/wp-json\/wp\/v2\/media?parent=2602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}